{"id":8,"date":"2014-03-10T09:41:17","date_gmt":"2014-03-10T08:41:17","guid":{"rendered":"http:\/\/www.cablabel.com\/fr\/?p=8"},"modified":"2025-03-26T09:50:49","modified_gmt":"2025-03-26T08:50:49","slug":"nouveau-cablabel-s3","status":"publish","type":"post","link":"https:\/\/www.cablabel.com\/fr\/2014\/03\/10\/nouveau-cablabel-s3\/","title":{"rendered":"NOUVEAU: cablabel\u00ae S3"},"content":{"rendered":"<p>cab&nbsp;technologies vous informe du lancement de son logiciel d\u2019\u00e9tiquetage cablabel\u00ae S3 issu de son propre d\u00e9veloppement. Avec ce logiciel, cab regroupe la cr\u00e9ation d\u2019\u00e9tiquette, la gestion et la surveillance de l\u2019impression de tous les syst\u00e8mes d\u2019\u00e9tiquetages cab, et synchronise le d\u00e9veloppement du mat\u00e9riel et du logiciel.<\/p>\n<p>cablabel\u00ae S3 permet d\u2019utiliser, comme aucun autre logiciel existant, toutes les possibilit\u00e9s des p\u00e9riph\u00e9riques cab : le logiciel utilise le langage JScript dans son int\u00e9gralit\u00e9. cablabel\u00ae S3 Pro importe les fichiers JScript existants afin de pouvoir utiliser le nouveau logiciel en peu de temps. Avec la nouvelle technologie de calques, l\u2019utilisateur cr\u00e9\u00e9 une seule \u00e9tiquette avec les donn\u00e9es pour tous les p\u00e9riph\u00e9riques et r\u00e9solutions utilis\u00e9s. La gestion intelligente de l\u2019impression d\u00e9termine, en fonction du p\u00e9riph\u00e9rique et de sa r\u00e9solution, les donn\u00e9es \u00e0 imprimer. Cela r\u00e9duit les possibilit\u00e9s d\u2019erreurs.<br \/>\n<!--more  Lire la suite  \u2192--><\/p>\n<p>Parall\u00e8lement, cablabel\u00ae S3 permet une int\u00e9gration optimale avec Database Connector pour la connexion aux bases de donn\u00e9es en mode autonome. Apr\u00e8s la cr\u00e9ation, le logiciel fourni \u00e0 l\u2019imprimante toutes les donn\u00e9es n\u00e9cessaires \u00e0 ce type de fonctionnement.<br \/>\nLes \u00e9tiquettes g\u00e9n\u00e9r\u00e9s avec cablabel\u00ae S3 sont nativement utilisables dans le cas d\u2019une utilisation d\u2019un syst\u00e8me d\u2019impression en mode autonome.<br \/>\nEn outre, il permet de cr\u00e9er des interfaces configurables conviviales pour la connexion vers SAP ou d\u2019autres p\u00e9riph\u00e9riques tels que des automates, des balances ou des lecteurs de code \u00e0 barre.<\/p>\n<p>Chaque entreprise organise diff\u00e9remment l&rsquo;impression de ses \u00e9tiquettes. Par exemple, la conception et la production sont souvent r\u00e9parties entre diff\u00e9rents employ\u00e9s. cab vous propose diff\u00e9rentes licences afin d&rsquo;adapter le logiciel de mani\u00e8re optimale \u00e0 votre entreprise :<br \/>\ncablabel\u00ae S3 Lite est livr\u00e9 gratuitement avec chaque imprimante et permet la cr\u00e9ation et l\u2019impression d\u2019\u00e9tiquettes.<br \/>\ncablabel\u00ae S3 Pro vous permet de cr\u00e9er des mod\u00e8les d&rsquo;\u00e9tiquettes pour l&rsquo;industrie professionnelle et de d\u00e9velopper vos propres applications pour l&rsquo;impression d&rsquo;\u00e9tiquettes.<br \/>\ncablabel\u00ae S3 Viewer montre l\u2019aper\u00e7u d\u2019une \u00e9tiquette dans l\u2019explorateur Windows et comme la version Lite, est livr\u00e9 gratuitement avec chaque imprimante. Le Viewer peut par exemple aider lors de la validation des processus ou les sp\u00e9cifications des fournisseurs.<br \/>\ncablabel\u00ae S3 Print est destin\u00e9 aux postes de productions d\u2019\u00e9tiquettes ou de marquages. L\u2019interface est \u00e9pur\u00e9e, seules les fonctions li\u00e9es \u00e0 l\u2019exploitation sont disponibles : l\u2019op\u00e9rateur s\u00e9lectionne sont \u00e9tiquette, la mise en page s\u2019affiche pour un contr\u00f4le visuel. Puis il saisit \u00e9ventuellement les informations variables du formulaire et la quantit\u00e9 \u00e0 produire. Cela simplifie le travail et r\u00e9duit les possibles sources d&rsquo;erreurs.<br \/>\nD\u2019autres versions comme cablabel\u00ae S3 Demo, Pro Laser, Print Laser et Print Server sont \u00e9galement en cours de pr\u00e9paration.<\/p>\n<p>cab propose sur son site internet les informations actuelles ainsi que des possibilit\u00e9s d\u2019\u00e9changer avec son support technique, pour une gestion optimale et un \u00e9change efficace des connaissances avec l\u2019utilisateur. Nous nous r\u00e9jouissons de vos commentaires !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>cab&nbsp;technologies vous informe du lancement de son logiciel d\u2019\u00e9tiquetage cablabel\u00ae S3 issu de son propre d\u00e9veloppement. Avec ce logiciel, cab regroupe la cr\u00e9ation d\u2019\u00e9tiquette, la gestion et la surveillance de l\u2019impression de tous les syst\u00e8mes d\u2019\u00e9tiquetages cab, et synchronise le &hellip; <a href=\"https:\/\/www.cablabel.com\/fr\/2014\/03\/10\/nouveau-cablabel-s3\/\">Continuer la lecture <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[37],"class_list":["post-8","post","type-post","status-publish","format-standard","hentry","category-general","tag-version"],"_links":{"self":[{"href":"https:\/\/www.cablabel.com\/fr\/wp-json\/wp\/v2\/posts\/8","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cablabel.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cablabel.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cablabel.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cablabel.com\/fr\/wp-json\/wp\/v2\/comments?post=8"}],"version-history":[{"count":5,"href":"https:\/\/www.cablabel.com\/fr\/wp-json\/wp\/v2\/posts\/8\/revisions"}],"predecessor-version":[{"id":860,"href":"https:\/\/www.cablabel.com\/fr\/wp-json\/wp\/v2\/posts\/8\/revisions\/860"}],"wp:attachment":[{"href":"https:\/\/www.cablabel.com\/fr\/wp-json\/wp\/v2\/media?parent=8"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cablabel.com\/fr\/wp-json\/wp\/v2\/categories?post=8"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cablabel.com\/fr\/wp-json\/wp\/v2\/tags?post=8"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}